{"id":1130,"date":"2023-09-04T19:54:49","date_gmt":"2023-09-04T11:54:49","guid":{"rendered":"https:\/\/opticalcutting.com\/?page_id=1130"},"modified":"2025-07-21T17:10:52","modified_gmt":"2025-07-21T09:10:52","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/www.opticalcutting.com\/fr\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"<h1 class=\"wp-block-heading\">Politique de confidentialit\u00e9<\/h1>\n\n\n\n<p>Last updated: September 04, 2025<\/p>\n\n\n\n<p>Cette politique de confidentialit\u00e9 d\u00e9crit nos politiques et proc\u00e9dures relatives \u00e0 la collecte, \u00e0 l&#039;utilisation et \u00e0 la divulgation de vos informations lorsque vous utilisez le service et vous informe de vos droits \u00e0 la vie priv\u00e9e et de la mani\u00e8re dont la loi vous prot\u00e8ge.<\/p>\n\n\n\n<p>Nous utilisons vos donn\u00e9es personnelles pour fournir et am\u00e9liorer le service. En utilisant le Service, vous acceptez la collecte et l&#039;utilisation d&#039;informations conform\u00e9ment \u00e0 la pr\u00e9sente politique de confidentialit\u00e9. Cette politique de confidentialit\u00e9 a \u00e9t\u00e9 cr\u00e9\u00e9e avec l&#039;aide de <a href=\"https:\/\/www.privacypolicies.com\/privacy-policy-generator\/\" target=\"_blank\" rel=\"noreferrer noopener\">G\u00e9n\u00e9rateur de politique de confidentialit\u00e9<\/a>.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Interpr\u00e9tation et d\u00e9finitions<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">Interpr\u00e9tation<\/h2>\n\n\n\n<p>Les mots dont la lettre initiale est en majuscule ont des significations d\u00e9finies dans les conditions suivantes. Les d\u00e9finitions suivantes auront la m\u00eame signification qu\u2019elles apparaissent au singulier ou au pluriel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00e9finitions<\/h2>\n\n\n\n<p>Aux fins de cette politique de confidentialit\u00e9\u00a0:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Compte<\/strong> d\u00e9signe un compte unique cr\u00e9\u00e9 pour vous permettre d&#039;acc\u00e9der \u00e0 notre service ou \u00e0 des parties de notre service.<\/li>\n\n\n\n<li><strong>Affilier<\/strong> d\u00e9signe une entit\u00e9 qui contr\u00f4le, est contr\u00f4l\u00e9e par ou est sous contr\u00f4le commun avec une partie, o\u00f9 \u00ab contr\u00f4le \u00bb d\u00e9signe la propri\u00e9t\u00e9 de 50% ou plus des actions, participations ou autres titres donnant droit \u00e0 voter pour l&#039;\u00e9lection d&#039;administrateurs ou d&#039;autres autorit\u00e9s de gestion.<\/li>\n\n\n\n<li><strong>Entreprise<\/strong> (d\u00e9sign\u00e9 par \u00ab la Soci\u00e9t\u00e9 \u00bb, \u00ab Nous \u00bb, \u00ab Notre \u00bb ou \u00ab Notre \u00bb dans le pr\u00e9sent Accord) fait r\u00e9f\u00e9rence \u00e0 Zhengzhou Shine Smart Equipment Ltd, Zhengzhou, Henan.<\/li>\n\n\n\n<li><strong>Biscuits<\/strong> sont de petits fichiers plac\u00e9s sur votre ordinateur, appareil mobile ou tout autre appareil par un site Web, contenant les d\u00e9tails de votre historique de navigation sur ce site Web parmi ses nombreuses utilisations.<\/li>\n\n\n\n<li><strong>Pays<\/strong> fait r\u00e9f\u00e9rence \u00e0 : Chine<\/li>\n\n\n\n<li><strong>Appareil<\/strong> d\u00e9signe tout appareil pouvant acc\u00e9der au Service tel qu&#039;un ordinateur, un t\u00e9l\u00e9phone portable ou une tablette num\u00e9rique.<\/li>\n\n\n\n<li><strong>Donn\u00e9es personnelles<\/strong> d\u00e9signe toute information relative \u00e0 une personne identifi\u00e9e ou identifiable.<\/li>\n\n\n\n<li><strong>Service<\/strong> fait r\u00e9f\u00e9rence au Site Internet.<\/li>\n\n\n\n<li><strong>Fournisseur de services<\/strong> d\u00e9signe toute personne physique ou morale qui traite les donn\u00e9es pour le compte de la Soci\u00e9t\u00e9. Il fait r\u00e9f\u00e9rence \u00e0 des soci\u00e9t\u00e9s tierces ou \u00e0 des personnes employ\u00e9es par la Soci\u00e9t\u00e9 pour faciliter le Service, pour fournir le Service au nom de la Soci\u00e9t\u00e9, pour ex\u00e9cuter des services li\u00e9s au Service ou pour aider la Soci\u00e9t\u00e9 \u00e0 analyser la mani\u00e8re dont le Service est utilis\u00e9.<\/li>\n\n\n\n<li><strong>Des donn\u00e9es d&#039;utilisation<\/strong> fait r\u00e9f\u00e9rence aux donn\u00e9es collect\u00e9es automatiquement, soit g\u00e9n\u00e9r\u00e9es par l&#039;utilisation du Service, soit \u00e0 partir de l&#039;infrastructure du Service elle-m\u00eame (par exemple, la dur\u00e9e d&#039;une visite d&#039;une page).<\/li>\n\n\n\n<li><strong>Site web<\/strong> fait r\u00e9f\u00e9rence \u00e0 une scie \u00e0 fil sans fin, accessible depuis <a href=\"https:\/\/www.opticalcutting.com\/fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.opticalcutting.com\/<\/a><\/li>\n\n\n\n<li><strong>Toi<\/strong> d\u00e9signe la personne acc\u00e9dant ou utilisant le Service, ou la soci\u00e9t\u00e9 ou autre entit\u00e9 juridique au nom de laquelle cette personne acc\u00e8de ou utilise le Service, selon le cas.<\/li>\n<\/ul>\n\n\n\n<h1 class=\"wp-block-heading\">Collecte et utilisation de vos donn\u00e9es personnelles<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">Types de donn\u00e9es collect\u00e9es<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Donn\u00e9es personnelles<\/h3>\n\n\n\n<p>Lors de l&#039;utilisation de notre service, nous pouvons vous demander de nous fournir certaines informations personnelles identifiables qui peuvent \u00eatre utilis\u00e9es pour vous contacter ou vous identifier. Les informations personnelles identifiables peuvent inclure, sans s\u2019y limiter\u00a0:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Adresse e-mail<\/li>\n\n\n\n<li>Pr\u00e9nom et nom<\/li>\n\n\n\n<li>Num\u00e9ro de t\u00e9l\u00e9phone<\/li>\n\n\n\n<li>Des donn\u00e9es d&#039;utilisation<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Des donn\u00e9es d&#039;utilisation<\/h3>\n\n\n\n<p>Les donn\u00e9es d&#039;utilisation sont collect\u00e9es automatiquement lors de l&#039;utilisation du service.<\/p>\n\n\n\n<p>Les donn\u00e9es d&#039;utilisation peuvent inclure des informations telles que l&#039;adresse de protocole Internet de votre appareil (par exemple, l&#039;adresse IP), le type de navigateur, la version du navigateur, les pages de notre service que vous visitez, l&#039;heure et la date de votre visite, le temps pass\u00e9 sur ces pages, l&#039;appareil unique. identifiants et autres donn\u00e9es de diagnostic.<\/p>\n\n\n\n<p>Lorsque vous acc\u00e9dez au Service via ou via un appareil mobile, nous pouvons collecter automatiquement certaines informations, notamment, mais sans s&#039;y limiter, le type d&#039;appareil mobile que vous utilisez, l&#039;identifiant unique de votre appareil mobile, l&#039;adresse IP de votre appareil mobile, votre syst\u00e8me d&#039;exploitation, le type de navigateur Internet mobile que vous utilisez, les identifiants uniques de l&#039;appareil et d&#039;autres donn\u00e9es de diagnostic.<\/p>\n\n\n\n<p>Nous pouvons \u00e9galement collecter des informations que votre navigateur envoie chaque fois que vous visitez notre service ou lorsque vous acc\u00e9dez au service via ou via un appareil mobile.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Technologies de suivi et cookies<\/h3>\n\n\n\n<p>Nous utilisons des cookies et des technologies de suivi similaires pour suivre l&#039;activit\u00e9 sur notre service et stocker certaines informations. Les technologies de suivi utilis\u00e9es sont des balises, des balises et des scripts pour collecter et suivre des informations et pour am\u00e9liorer et analyser notre service. Les technologies que nous utilisons peuvent inclure\u00a0:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Cookies ou cookies de navigateur.<\/strong> Un cookie est un petit fichier plac\u00e9 sur votre appareil. Vous pouvez demander \u00e0 Votre navigateur de refuser tous les Cookies ou d&#039;indiquer lorsqu&#039;un Cookie est envoy\u00e9. Cependant, si vous n&#039;acceptez pas les cookies, vous ne pourrez peut-\u00eatre pas utiliser certaines parties de notre service. Sauf si vous avez ajust\u00e9 les param\u00e8tres de votre navigateur afin qu&#039;il refuse les cookies, notre service peut utiliser des cookies.<\/li>\n\n\n\n<li><strong>Balises Web.<\/strong> Certaines sections de notre Service et nos e-mails peuvent contenir de petits fichiers \u00e9lectroniques appel\u00e9s balises Web (\u00e9galement appel\u00e9es gifs clairs, balises pixel et gifs \u00e0 pixel unique) qui permettent \u00e0 la Soci\u00e9t\u00e9, par exemple, de compter les utilisateurs qui ont visit\u00e9 ces pages. ou ouvert un e-mail et pour d&#039;autres statistiques connexes sur le site Web (par exemple, enregistrer la popularit\u00e9 d&#039;une certaine section et v\u00e9rifier l&#039;int\u00e9grit\u00e9 du syst\u00e8me et du serveur).<\/li>\n<\/ul>\n\n\n\n<p>Les cookies peuvent \u00eatre des cookies \u00ab persistants \u00bb ou \u00ab de session \u00bb. Les cookies persistants restent sur votre ordinateur personnel ou appareil mobile lorsque vous vous d\u00e9connectez, tandis que les cookies de session sont supprim\u00e9s d\u00e8s que vous fermez votre navigateur Web. En savoir plus sur les cookies sur le <a href=\"https:\/\/www.privacypolicies.com\/blog\/privacy-policy-template\/#Use_Of_Cookies_Log_Files_And_Tracking\" target=\"_blank\" rel=\"noreferrer noopener\">Site Web des politiques de confidentialit\u00e9<\/a> article.<\/p>\n\n\n\n<p>Nous utilisons \u00e0 la fois des cookies de session et des cookies persistants aux fins \u00e9nonc\u00e9es ci-dessous\u00a0:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Cookies n\u00e9cessaires\/essentiels<\/strong> Type : Cookies de session G\u00e9r\u00e9s par : Nous Finalit\u00e9 : Ces Cookies sont essentiels pour vous fournir les services disponibles via le site Web et pour vous permettre d&#039;utiliser certaines de ses fonctionnalit\u00e9s. Ils aident \u00e0 authentifier les utilisateurs et \u00e0 pr\u00e9venir l&#039;utilisation frauduleuse des comptes d&#039;utilisateurs. Sans ces cookies, les services que vous avez demand\u00e9s ne peuvent pas \u00eatre fournis et nous utilisons ces cookies uniquement pour vous fournir ces services.<\/li>\n\n\n\n<li><strong>Politique de cookies \/ Avis Acceptation Cookies<\/strong> Type : Cookies persistants G\u00e9r\u00e9s par : Nous Objectif : Ces cookies identifient si les utilisateurs ont accept\u00e9 l&#039;utilisation de cookies sur le site Web.<\/li>\n\n\n\n<li><strong>Cookies de fonctionnalit\u00e9<\/strong> Type : Cookies persistants G\u00e9r\u00e9s par : Nous Objectif : Ces cookies nous permettent de m\u00e9moriser les choix que vous faites lorsque vous utilisez le site Web, comme la m\u00e9morisation de vos informations de connexion ou de vos pr\u00e9f\u00e9rences linguistiques. La finalit\u00e9 de ces Cookies est de Vous offrir une exp\u00e9rience plus personnelle et de Vous \u00e9viter de devoir saisir \u00e0 nouveau vos pr\u00e9f\u00e9rences \u00e0 chaque fois que Vous utilisez le Site Internet.<\/li>\n<\/ul>\n\n\n\n<p>Pour plus d&#039;informations sur les cookies que nous utilisons et vos choix concernant les cookies, veuillez consulter notre Politique de cookies ou la section Cookies de notre Politique de confidentialit\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Utilisation de vos donn\u00e9es personnelles<\/h2>\n\n\n\n<p>La Soci\u00e9t\u00e9 peut utiliser les Donn\u00e9es Personnelles aux fins suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Pour fournir et maintenir notre service<\/strong>, y compris pour surveiller l&#039;utilisation de notre Service.<\/li>\n\n\n\n<li><strong>Pour g\u00e9rer votre compte\u00a0:<\/strong> pour g\u00e9rer votre inscription en tant qu&#039;utilisateur du Service. Les Donn\u00e9es Personnelles que Vous fournissez peuvent Vous donner acc\u00e8s \u00e0 diff\u00e9rentes fonctionnalit\u00e9s du Service qui Vous sont accessibles en tant qu&#039;utilisateur enregistr\u00e9.<\/li>\n\n\n\n<li><strong>Pour l&#039;ex\u00e9cution d&#039;un contrat :<\/strong> l&#039;\u00e9laboration, le respect et l&#039;ex\u00e9cution du contrat d&#039;achat des produits, articles ou services que vous avez achet\u00e9s ou de tout autre contrat avec nous via le Service.<\/li>\n\n\n\n<li><strong>Te contacter:<\/strong> Pour vous contacter par e-mail, appels t\u00e9l\u00e9phoniques, SMS ou autres formes de communication \u00e9lectronique \u00e9quivalentes, telles que les notifications push d&#039;une application mobile concernant les mises \u00e0 jour ou les communications informatives li\u00e9es aux fonctionnalit\u00e9s, produits ou services sous contrat, y compris les mises \u00e0 jour de s\u00e9curit\u00e9, lorsque cela est n\u00e9cessaire ou raisonnable. pour leur mise en \u0153uvre.<\/li>\n\n\n\n<li><strong>Pour vous fournir<\/strong> avec des actualit\u00e9s, des offres sp\u00e9ciales et des informations g\u00e9n\u00e9rales sur d&#039;autres biens, services et \u00e9v\u00e9nements que nous proposons et similaires \u00e0 ceux que vous avez d\u00e9j\u00e0 achet\u00e9s ou sur lesquels vous avez demand\u00e9 des renseignements, \u00e0 moins que vous ayez choisi de ne pas recevoir de telles informations.<\/li>\n\n\n\n<li><strong>Pour g\u00e9rer vos demandes :<\/strong> Pour r\u00e9pondre et g\u00e9rer vos demandes aupr\u00e8s de nous.<\/li>\n\n\n\n<li><strong>Pour les transmissions d&#039;entreprises :<\/strong> Nous pouvons utiliser vos informations pour \u00e9valuer ou proc\u00e9der \u00e0 une fusion, une cession, une restructuration, une r\u00e9organisation, une dissolution ou toute autre vente ou transfert de tout ou partie de nos actifs, que ce soit dans le cadre d&#039;une activit\u00e9 en activit\u00e9 ou dans le cadre d&#039;une faillite, d&#039;une liquidation ou d&#039;une proc\u00e9dure similaire. dans lequel les donn\u00e9es personnelles que nous d\u00e9tenons sur les utilisateurs de nos services font partie des actifs transf\u00e9r\u00e9s.<\/li>\n\n\n\n<li><strong>\u00c0 d&#039;autres fins<\/strong>: Nous pouvons utiliser vos informations \u00e0 d&#039;autres fins, telles que l&#039;analyse de donn\u00e9es, l&#039;identification des tendances d&#039;utilisation, la d\u00e9termination de l&#039;efficacit\u00e9 de nos campagnes promotionnelles et pour \u00e9valuer et am\u00e9liorer notre service, nos produits, nos services, notre marketing et votre exp\u00e9rience.<\/li>\n<\/ul>\n\n\n\n<p>Nous pouvons partager vos informations personnelles dans les situations suivantes\u00a0:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Avec les prestataires de services\u00a0:<\/strong> Nous pouvons partager vos informations personnelles avec des fournisseurs de services pour surveiller et analyser l&#039;utilisation de notre service et pour vous contacter.<\/li>\n\n\n\n<li><strong>Pour les transmissions d&#039;entreprises :<\/strong> Nous pouvons partager ou transf\u00e9rer vos informations personnelles dans le cadre de, ou pendant les n\u00e9gociations de, toute fusion, vente d&#039;actifs de la soci\u00e9t\u00e9, financement ou acquisition de tout ou partie de notre entreprise \u00e0 une autre soci\u00e9t\u00e9.<\/li>\n\n\n\n<li><strong>Avec les affili\u00e9s\u00a0:<\/strong> Nous pouvons partager vos informations avec nos affili\u00e9s, auquel cas nous demanderons \u00e0 ces affili\u00e9s de respecter cette politique de confidentialit\u00e9. Les soci\u00e9t\u00e9s affili\u00e9es comprennent notre soci\u00e9t\u00e9 m\u00e8re et toutes autres filiales, partenaires de coentreprise ou autres soci\u00e9t\u00e9s que nous contr\u00f4lons ou qui sont sous contr\u00f4le commun avec nous.<\/li>\n\n\n\n<li><strong>Avec des partenaires commerciaux :<\/strong> Nous pouvons partager vos informations avec nos partenaires commerciaux pour vous proposer certains produits, services ou promotions.<\/li>\n\n\n\n<li><strong>Avec d&#039;autres utilisateurs\u00a0:<\/strong> lorsque vous partagez des informations personnelles ou interagissez de toute autre mani\u00e8re dans les espaces publics avec d&#039;autres utilisateurs, ces informations peuvent \u00eatre consult\u00e9es par tous les utilisateurs et peuvent \u00eatre distribu\u00e9es publiquement \u00e0 l&#039;ext\u00e9rieur.<\/li>\n\n\n\n<li><strong>Avec votre consentement<\/strong>: Nous pouvons divulguer vos informations personnelles \u00e0 toute autre fin avec votre consentement.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Conservation de vos donn\u00e9es personnelles<\/h2>\n\n\n\n<p>La Soci\u00e9t\u00e9 conservera vos donn\u00e9es personnelles uniquement aussi longtemps que n\u00e9cessaire aux fins \u00e9nonc\u00e9es dans la pr\u00e9sente politique de confidentialit\u00e9. Nous conserverons et utiliserons vos donn\u00e9es personnelles dans la mesure n\u00e9cessaire pour nous conformer \u00e0 nos obligations l\u00e9gales (par exemple, si nous sommes tenus de conserver vos donn\u00e9es pour nous conformer aux lois applicables), r\u00e9soudre les litiges et faire respecter nos accords et politiques juridiques.<\/p>\n\n\n\n<p>La Soci\u00e9t\u00e9 conservera \u00e9galement les donn\u00e9es d&#039;utilisation \u00e0 des fins d&#039;analyse interne. Les donn\u00e9es d&#039;utilisation sont g\u00e9n\u00e9ralement conserv\u00e9es pendant une p\u00e9riode plus courte, sauf lorsque ces donn\u00e9es sont utilis\u00e9es pour renforcer la s\u00e9curit\u00e9 ou pour am\u00e9liorer la fonctionnalit\u00e9 de notre service, ou lorsque nous sommes l\u00e9galement tenus de conserver ces donn\u00e9es pendant des p\u00e9riodes plus longues.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Transfert de vos donn\u00e9es personnelles<\/h2>\n\n\n\n<p>Vos informations, y compris vos donn\u00e9es personnelles, sont trait\u00e9es dans les bureaux op\u00e9rationnels de la Soci\u00e9t\u00e9 et dans tout autre endroit o\u00f9 se trouvent les parties impliqu\u00e9es dans le traitement. Cela signifie que ces informations peuvent \u00eatre transf\u00e9r\u00e9es et conserv\u00e9es sur des ordinateurs situ\u00e9s en dehors de votre \u00e9tat, province, pays ou autre juridiction gouvernementale o\u00f9 les lois sur la protection des donn\u00e9es peuvent diff\u00e9rer de celles de votre juridiction.<\/p>\n\n\n\n<p>Votre consentement \u00e0 cette politique de confidentialit\u00e9 suivi de votre soumission de ces informations repr\u00e9sente votre accord \u00e0 ce transfert.<\/p>\n\n\n\n<p>La Soci\u00e9t\u00e9 prendra toutes les mesures raisonnablement n\u00e9cessaires pour garantir que vos donn\u00e9es sont trait\u00e9es de mani\u00e8re s\u00e9curis\u00e9e et conform\u00e9ment \u00e0 la pr\u00e9sente politique de confidentialit\u00e9 et aucun transfert de vos donn\u00e9es personnelles n&#039;aura lieu vers une organisation ou un pays \u00e0 moins que des contr\u00f4les ad\u00e9quats ne soient en place, y compris la s\u00e9curit\u00e9 de Vos donn\u00e9es et autres informations personnelles.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Supprimez vos donn\u00e9es personnelles<\/h2>\n\n\n\n<p>Vous avez le droit de supprimer ou de demander que nous vous aidions \u00e0 supprimer les donn\u00e9es personnelles que nous avons collect\u00e9es \u00e0 votre sujet.<\/p>\n\n\n\n<p>Notre Service peut vous donner la possibilit\u00e9 de supprimer certaines informations vous concernant du Service.<\/p>\n\n\n\n<p>Vous pouvez mettre \u00e0 jour, modifier ou supprimer vos informations \u00e0 tout moment en vous connectant \u00e0 votre compte, si vous en avez un, et en visitant la section des param\u00e8tres du compte qui vous permet de g\u00e9rer vos informations personnelles. Vous pouvez \u00e9galement nous contacter pour demander l&#039;acc\u00e8s, la correction ou la suppression de toute information personnelle que vous nous avez fournie.<\/p>\n\n\n\n<p>Veuillez toutefois noter que nous pouvons \u00eatre amen\u00e9s \u00e0 conserver certaines informations lorsque nous avons une obligation l\u00e9gale ou une base l\u00e9gale de le faire.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Divulgation de vos donn\u00e9es personnelles<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Transactions commerciales<\/h3>\n\n\n\n<p>Si la Soci\u00e9t\u00e9 est impliqu\u00e9e dans une fusion, une acquisition ou une vente d&#039;actifs, vos donn\u00e9es personnelles peuvent \u00eatre transf\u00e9r\u00e9es. Nous vous informerons avant que vos donn\u00e9es personnelles ne soient transf\u00e9r\u00e9es et ne soient soumises \u00e0 une politique de confidentialit\u00e9 diff\u00e9rente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Forces de l&#039;ordre<\/h3>\n\n\n\n<p>Dans certaines circonstances, la Soci\u00e9t\u00e9 peut \u00eatre tenue de divulguer vos donn\u00e9es personnelles si la loi l&#039;y oblige ou en r\u00e9ponse \u00e0 des demandes valables des autorit\u00e9s publiques (par exemple un tribunal ou un organisme gouvernemental).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Autres exigences l\u00e9gales<\/h3>\n\n\n\n<p>La Soci\u00e9t\u00e9 peut divulguer vos donn\u00e9es personnelles en croyant de bonne foi qu&#039;une telle action est n\u00e9cessaire pour\u00a0:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Se conformer \u00e0 une obligation l\u00e9gale<\/li>\n\n\n\n<li>Prot\u00e9ger et d\u00e9fendre les droits ou les biens de la Soci\u00e9t\u00e9<\/li>\n\n\n\n<li>Pr\u00e9venir ou enqu\u00eater sur d&#039;\u00e9ventuels actes r\u00e9pr\u00e9hensibles en relation avec le Service<\/li>\n\n\n\n<li>Prot\u00e9ger la s\u00e9curit\u00e9 personnelle des Utilisateurs du Service ou du public<\/li>\n\n\n\n<li>Se prot\u00e9ger contre la responsabilit\u00e9 l\u00e9gale<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">S\u00e9curit\u00e9 de vos donn\u00e9es personnelles<\/h2>\n\n\n\n<p>La s\u00e9curit\u00e9 de vos donn\u00e9es personnelles est importante pour nous, mais n&#039;oubliez pas qu&#039;aucune m\u00e9thode de transmission sur Internet ou m\u00e9thode de stockage \u00e9lectronique n&#039;est s\u00e9curis\u00e9e 100%. Bien que nous nous efforcions d&#039;utiliser des moyens commercialement acceptables pour prot\u00e9ger vos donn\u00e9es personnelles, nous ne pouvons garantir leur s\u00e9curit\u00e9 absolue.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Confidentialit\u00e9 des enfants<\/h1>\n\n\n\n<p>Notre service ne s&#039;adresse pas aux personnes de moins de 13 ans. Nous ne collectons sciemment aucune information personnelle identifiable aupr\u00e8s de toute personne de moins de 13 ans. Si vous \u00eates un parent ou un tuteur et que vous savez que votre enfant nous a fourni des donn\u00e9es personnelles, veuillez Contactez-nous. Si nous apprenons que nous avons collect\u00e9 des donn\u00e9es personnelles aupr\u00e8s d&#039;une personne de moins de 13 ans sans v\u00e9rification du consentement parental, nous prenons des mesures pour supprimer ces informations de nos serveurs.<\/p>\n\n\n\n<p>Si nous devons nous appuyer sur le consentement comme base l\u00e9gale pour traiter vos informations et que votre pays exige le consentement d&#039;un parent, nous pouvons exiger le consentement de votre parent avant de collecter et d&#039;utiliser ces informations.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Liens vers d&#039;autres sites Web<\/h1>\n\n\n\n<p>Notre Service peut contenir des liens vers d&#039;autres sites Web qui ne sont pas exploit\u00e9s par Nous. Si vous cliquez sur un lien tiers, vous serez dirig\u00e9 vers le site de ce tiers. Nous vous conseillons fortement de consulter la politique de confidentialit\u00e9 de chaque site que vous visitez.<\/p>\n\n\n\n<p>Nous n&#039;avons aucun contr\u00f4le et n&#039;assumons aucune responsabilit\u00e9 quant au contenu, aux politiques de confidentialit\u00e9 ou aux pratiques de tout site ou service tiers.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Modifications de cette politique de confidentialit\u00e9<\/h1>\n\n\n\n<p>Nous pouvons mettre \u00e0 jour notre politique de confidentialit\u00e9 de temps \u00e0 autre. Nous vous informerons de tout changement en publiant la nouvelle politique de confidentialit\u00e9 sur cette page.<\/p>\n\n\n\n<p>Nous vous en informerons par e-mail et\/ou par un avis bien visible sur notre service, avant que le changement n&#039;entre en vigueur et mettrons \u00e0 jour la date de \u00ab Derni\u00e8re mise \u00e0 jour \u00bb en haut de cette politique de confidentialit\u00e9.<\/p>\n\n\n\n<p>Il vous est conseill\u00e9 de consulter p\u00e9riodiquement cette politique de confidentialit\u00e9 pour tout changement. Les modifications apport\u00e9es \u00e0 cette politique de confidentialit\u00e9 entrent en vigueur d\u00e8s leur publication sur cette page.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Contactez-nous<\/h1>\n\n\n\n<p>Si vous avez des questions concernant cette politique de confidentialit\u00e9, vous pouvez nous contacter\u00a0:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>By email: levy@www.endlesswiresaw.com<\/li>\n<\/ul>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Privacy Policy Last updated: September 04, 2025 This Privacy Policy describes Our policies and procedures on the collection, use and disclosure of Your information when You use the Service and tells You about Your privacy rights and how the law protects You. We use Your Personal data to provide and improve the Service. By using [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1130","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.opticalcutting.com\/fr\/wp-json\/wp\/v2\/pages\/1130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opticalcutting.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.opticalcutting.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.opticalcutting.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opticalcutting.com\/fr\/wp-json\/wp\/v2\/comments?post=1130"}],"version-history":[{"count":0,"href":"https:\/\/www.opticalcutting.com\/fr\/wp-json\/wp\/v2\/pages\/1130\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.opticalcutting.com\/fr\/wp-json\/wp\/v2\/media?parent=1130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}